{"id":8203,"date":"2023-04-24T01:42:53","date_gmt":"2023-04-23T23:42:53","guid":{"rendered":"https:\/\/contabo.com\/blog\/?p=8203"},"modified":"2023-04-24T01:42:56","modified_gmt":"2023-04-23T23:42:56","slug":"gui-und-xrdp-unter-ubuntu-und-centos-unstallieren","status":"publish","type":"post","link":"https:\/\/contabo.com\/blog\/de\/gui-und-xrdp-unter-ubuntu-und-centos-unstallieren\/","title":{"rendered":"Wie man eine GUI und XRDP auf Ubuntu und CentOS installiert"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg\" alt=\"GUI unter Ubuntu und CentOS installiert (head image)\" class=\"wp-image-16926\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg 1200w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS-600x315.jpg 600w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS-768x403.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>Eigentlich ist es nicht notwendig, eine grafische Benutzeroberfl\u00e4che (GUI) auf einem Linux-basierten System zu installieren, da es immer die M\u00f6glichkeit gibt, das System \u00fcber SSH zu verwalten und zu konfigurieren. Allerdings hat eine GUI zweifellos ihre Vorteile. Insbesondere f\u00fcr erfahrene Windows-Anwender, die noch nie zuvor ein Terminal benutzt haben, ist eine GUI unter Linux eine alternative M\u00f6glichkeit, einen Linux-basierten Server zu nutzen, ohne f\u00fcr eine Windows-Lizenz zus\u00e4tzliches Geld zu bezahlen. Dar\u00fcber hinaus kann eine GUI die Arbeit erleichtern und einige komplizierte Aufgaben \u00fcbersichtlicher machen. Das bedeutet nicht, dass auf das Terminal g\u00e4nzlich verzichtet werden kann, aber viele Aufgaben, wie das Bearbeiten von Konfigurationsdateien oder das Verwalten der Dateistruktur in einem Dateimanager k\u00f6nnen deutlich einfacher erledigt werden.<\/p>\n\n\n\n<p>Im folgenden Tutorial stellen wir euch alle Informationen bereit, damit jeder eine GUI und XRDP auf CentOS- und Debian-basierten System mit XFCE4 als Desktop-Umgebung installieren kann, und zeigt, wie man sich anschlie\u00dfend mit dem Server verbindet. Das Tutorial ist in drei Teile gegliedert: Erf\u00fcllung der Voraussetzungen, Installation und Konfiguration der Software und schlie\u00dflich die Verbindung zum System.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-voraussetzungen\">Voraussetzungen<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ein bereits installierter VPS\/Dedicated Server mit einem beliebigen Linux-Betriebssystem. <\/li>\n\n\n\n<li> Eine funktionierende Internetverbindung, um zus\u00e4tzliche Pakete auf dem Remote-Server zu installieren und sich von der lokalen Maschine aus mit dem Remote-Server zu verbinden. <\/li>\n\n\n\n<li> Einen VNC-Client oder SSH-Client, um sich von Ihrem lokalen Ger\u00e4t aus mit dem Server zu verbinden. <\/li>\n\n\n\n<li> Einen Benutzer, der sich am Betriebssystem anmelden darf.<\/li>\n\n\n\n<li> Etwas Arbeit am Terminal entweder \u00fcber SSH oder VNC <\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-weitere-informationen-zur-installation\">Weitere Informationen zur Installation<\/h2>\n\n\n\n<p>Es ist nicht notwendig, dass der Server neu installiert wird, da es jederzeit m\u00f6glich ist, die GUI und XRDP auf einem bereits installierten und konfigurierten Server zu installieren.<\/p>\n\n\n\n<p>Um den Benutzer zu erstellen und die notwendige Software zu installieren, m\u00fcssen Sie sich entweder \u00fcber VNC auf einem VPS oder \u00fcber SSH auf einem VPS oder Dedicated Server mit dem Server verbinden. Dazu haben wir bereits gute Tutorials, auf die Sie verweisen k\u00f6nnen:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>  <\/th><th> VPS <\/th><th>\n\t\t\t\tDedicated Server\n\t\t\t<\/th><\/tr><\/thead><tbody><tr><td>\n\t\t\t\t<strong>SSH<\/strong>\n\t\t\t<\/td><td> <a href=\"https:\/\/contabo.de\/?show=tutorials&amp;tutorial=verbindungsaufbau-ssh\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Mehr  Informationen<\/a> <\/td><td> <a href=\"https:\/\/contabo.com\/blog\/de\/verbindungsaufbau-ssh\" target=\"_blank\" rel=\"noreferrer noopener\">Mehr Informationen<\/a><\/td><\/tr><tr><td>\n\t\t\t\t<strong>VNC<\/strong>\n\t\t\t<\/td><td> <a href=\"https:\/\/contabo.de\/?show=tutorials&amp;tutorial=wie-stelle-ich-eine-verbindung-zu-meinem-vps-mit-vnc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Mehr Informationen<\/a> <\/td><td>Nicht unterst\u00fctzt<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Ein Benutzer wird ben\u00f6tigt, um sich nach dem Aufbau der RDP-Sitzung am System anzumelden. Dies kann nicht der Benutzer-Root sein, dieser ist aus Sicherheitsgr\u00fcnden zur Anmeldung an die grafische Oberfl\u00e4che deaktiviert. Wir empfehlen auch nicht, direkt als Benutzer-Root zu arbeiten, sondern mit einem Benutzer, der in der Lage ist, seine Privilegien durch den Befehl &#8217;sudo&#8216; zu erweitern, um Aufgaben auszuf\u00fchren, bei denen Root-Rechte erforderlich sind. Wenn du mehr \u00fcber den root-Benutzer und den &#8222;sudo&#8220;-Befehl erfahren willst, klicke hier.<\/p>\n\n\n\n<p>Bitte beachten Sie, wenn Sie sich f\u00fcr die Verwendung von VNC entscheiden, m\u00fcssen Sie sich zuerst mit Ihren Root-Anmeldeinformationen am System anmelden. Bei Verwendung von SSH ist dies nicht notwendig, da Sie direkt als entsprechender Benutzer im System angemeldet werden, der in unserem Fall root ist. Nach dem Einloggen erstellen wir zun\u00e4chst den Benutzer:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>useradd -m -s \/bin\/bash USERNAME<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-code\"><code>passwd USERNAME<\/code><\/pre>\n\n\n\n<p>Diese Befehle erstellen zuerst einen Benutzer mit dem Namen USERNAME und seinem Heimatverzeichnis in \/home\/USERNAME mit bash als bevorzugter Shell. Mit dem zweiten Befehl kannst du ein Passwort f\u00fcr den Benutzer vergeben. Bitte ersetzen Sie den USERNAME durch einen beliebigen Namen.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"149\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.create_user-1.jpg\" alt=\"GUI unter Ubuntu und CentOS installiert\" class=\"wp-image-8211\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.create_user-1.jpg 501w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.create_user-1-300x89.jpg 300w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/figure>\n\n\n\n<p>Dies sind alles Voraussetzungen und wir haben jetzt den ersten Teil abgeschlossen. Bitte schlie\u00dfen Sie die Verbindung zu Ihrem Server nicht, da wir sie auch f\u00fcr den zweiten Teil dieses Tutorials ben\u00f6tigen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-installation-und-konfiguration-von-xrdp-und-der-gui\">Installation und konfiguration von XRDP und der GUI<\/h2>\n\n\n\n<p>Obwohl XRDP auch ohne GUI l\u00e4uft, ist eine GUI erforderlich, um sich am Server anzumelden. Deshalb m\u00fcssen wir beides installieren.<\/p>\n\n\n\n<p>Sowohl XRDP als auch die GUI k\u00f6nnen \u00fcber die Paketverwaltung installiert werden. Je nachdem, welches System Sie verwenden, sind die Befehle unterschiedlich. Bitte beachten Sie im Folgenden die Befehle f\u00fcr Ubuntu und CentOS:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Ubuntu basierte Systeme <\/th><th>\n\t\t\t\tCentOS\n\t\t\t<\/th><\/tr><\/thead><tbody><tr><td>apt update<br>apt install xrdp vnc4server xubuntu-desktop <\/td><td>yum install -y epel-release<br><code>yum groupinstall \"Server with GUI\" -y<\/code><br><code>yum -y install<\/code> <code>xrdp tigervnc-server<\/code> <\/td><\/tr><tr><td>Aktualisieren Sie zun\u00e4chst die Paketmanager-Datenbank und installieren Sie dann XRDP und die GUI. <\/td><td>Installieren Sie zuerst die &#8222;Extra packages for enterprise Linux&#8220;, die XRDP erst verf\u00fcgbar machen. Die folgenden beiden Befehle installieren eine GUI und XRDP in Kombination mit einem VNC-Server.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Wenn alle Befehle fehlerfrei beendet wurden, ist XRDP erfolgreich installiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-konfiguration-von-xrdp\">Konfiguration von XRDP<\/h2>\n\n\n\n<p>Sobald XRDP installiert ist, sollte es sofort funktionieren. Wir sollten jedoch zumindest die TLS-Verschl\u00fcsselung aktivieren, um die Kommunikation zwischen dem Client und dem Server zu sichern. Obwohl die Installation von XRDP bereits ein Zertifikat beinhaltet, werden wir unser eigenes erstellen, indem wir nur folgenden Befehl ausf\u00fchren:<\/p>\n\n\n\n<p>openssl\nreq -x509 -newkey rsa:2048 -nodes -keyout xrdp.key.pem -out\nxrdp.cert.pem -days 365<\/p>\n\n\n\n<p>Dadurch werden zwei Dateien erstellt, xrdp.key.pem und xrdp.cert.pem, jeweils im Heimatverzeichnis des aktuellen Benutzers, mit dem Sie angemeldet sind. Passen Sie dann die Dateiberechtigungen an, um zu verhindern, dass andere den privaten Schl\u00fcssel lesen k\u00f6nnen:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>chown root:root xrdp*.pem<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-code\"><code>chmod 640 xrdp*.pem<\/code><\/pre>\n\n\n\n<p>Dann verschieben Sie diese Dateien nach \/etc\/xrdp:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>mv xrdp*.pem \/etc\/xrdp<\/code><\/pre>\n\n\n\n<p>Nun ist es an der Zeit, die XRDP-Konfiguration zu \u00e4ndern. Bitte \u00f6ffnen Sie dazu die Datei xrdp.ini mit Ihrem bevorzugten Texteditor:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>nano \/etc\/xrdp\/xrdp.ini<\/code><\/pre>\n\n\n\n<p>und \u00e4ndern Sie die entsprechenden Zeilen security_layer, certificate und key_file wie im Screenshot unten gezeigt:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"231\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.tls_-1.jpg\" alt=\"GUI unter Ubuntu und CentOS installiert\" class=\"wp-image-8214\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.tls_-1.jpg 760w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2019\/10\/xrdp.tls_-1-300x91.jpg 300w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<p>Nun m\u00fcssen wir pr\u00fcfen, ob das System in die grafische Oberfl\u00e4che startet. Um dies zu \u00fcberpr\u00fcfen, geben Sie den folgenden Befehl ein:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>systemctl get-default<\/code><\/pre>\n\n\n\n<p>Sie sollten jetzt folgende Ausgabe im Terminal sehen:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>graphical.target<\/code><\/pre>\n\n\n\n<p>Wenn dies nicht der Fall ist, geben Sie bitte folgendes ein, um das grafische Oberfl\u00e4che zu aktivieren:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>systemctl set-default graphical.target<\/code><\/pre>\n\n\n\n<p>und \u00fcberpr\u00fcfen Sie mit dem obigen Befehl, ob dies erfolgreich eingestellt wurde. Aktivieren Sie schlie\u00dflich den xrdp-Server, indem Sie den Befehl eingeben:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>systemctl enable xrdp.service<\/code><\/pre>\n\n\n\n<p>Stellen Sie dann die entsprechende Desktop-Umgebung f\u00fcr den zuvor angelegten Benutzer ein:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>echo \u201exfce4-session\u201c > \/home\/USERNAME\/.xsession<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-code\"><code>chown USERNAME: \/home\/USERNAME\/.xsession<\/code><\/pre>\n\n\n\n<p>Starten Sie anschlie\u00dfend Ihren Server neu. Nach dem Neustart des Servers sollten Sie sich \u00fcber RDP mit dem Server verbinden k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Artikel erf\u00e4hrst du, wie du eine GUI unter Ubuntu und CentOS installiert. Erfahre au\u00dferdem, welche Vorteile eine GUI bietet.<\/p>\n","protected":false},"author":32,"featured_media":16926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1399],"tags":[],"ppma_author":[1504],"class_list":["post-8203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutorials"],"uagb_featured_image_src":{"full":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg",1200,630,false],"thumbnail":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS-150x150.jpg",150,150,true],"medium":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS-600x315.jpg",600,315,true],"medium_large":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS-768x403.jpg",768,403,true],"large":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg",1200,630,false],"1536x1536":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg",1200,630,false],"2048x2048":["https:\/\/contabo.com\/blog\/wp-content\/uploads\/2023\/04\/blog-head_how2-install-a-GUI-and-XRDP-on-Ubuntu-and-CentOS.jpg",1200,630,false]},"uagb_author_info":{"display_name":"Michael","author_link":"https:\/\/contabo.com\/blog\/de\/author\/michaelj\/"},"uagb_comment_info":0,"uagb_excerpt":"In diesem Artikel erf\u00e4hrst du, wie du eine GUI unter Ubuntu und CentOS installiert. Erfahre au\u00dferdem, welche Vorteile eine GUI bietet.","authors":[{"term_id":1504,"user_id":32,"is_guest":0,"slug":"michaelj","display_name":"Michael","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/6d6cdf09cae3aa60e4bc9fb09ae1551ac9978016ad93e36ec87f26dabb400108?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts\/8203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=8203"}],"version-history":[{"count":1,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts\/8203\/revisions"}],"predecessor-version":[{"id":16932,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts\/8203\/revisions\/16932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/media\/16926"}],"wp:attachment":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=8203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=8203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=8203"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/ppma_author?post=8203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}