{"id":4498,"date":"2015-12-18T14:15:55","date_gmt":"2015-12-18T12:15:55","guid":{"rendered":"https:\/\/contabo.com\/blog\/?p=4498"},"modified":"2021-02-20T10:58:59","modified_gmt":"2021-02-20T09:58:59","slug":"windows-updates-bearbeiten-ws-2008","status":"publish","type":"post","link":"https:\/\/contabo.com\/blog\/de\/windows-updates-bearbeiten-ws-2008\/","title":{"rendered":"Windows Updates bearbeiten (WS 2008)"},"content":{"rendered":"\n<p>In diesem Tutorial m\u00f6chten wir Ihnen erkl\u00e4ren, wie Sie automatische Updates bei Windows 2008 auf Ihrem Server aktivieren und deaktivieren oder auch den Zeitpunkt f\u00fcr diese Updates bestimmen k\u00f6nnen.<\/p>\n\n\n\n<p>1. Bitte verbinden Sie sich \u00fcber RDP mit Ihrem Server und \u00f6ffnen Sie die Systemsteuerung:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1197\" height=\"362\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1.png\" alt=\"WS Updates 2008 DE Bild 1\" class=\"wp-image-4499\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1.png 1197w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1-300x91.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1-1024x310.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-1-768x232.png 768w\" sizes=\"auto, (max-width: 1197px) 100vw, 1197px\" \/><\/a><\/figure>\n\n\n\n<p>2. Unter dem Punkt \u201eSystem und Sicherheit\u201c finden Sie die gew\u00fcnschte Option \u201eWindows Update\u201c:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1188\" height=\"374\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2.png\" alt=\"WS Updates 2008 DE Bild 2\" class=\"wp-image-4500\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2.png 1188w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2-300x94.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2-1024x322.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2015\/11\/WS-Updates-2008-DE-Bild-2-768x242.png 768w\" sizes=\"auto, (max-width: 1188px) 100vw, 1188px\" \/><\/a><\/figure>\n\n\n\n<p>3. Anschlie\u00dfend werden Sie auf folgende Seite weiter geleitet (Leider wird ab diesem Zeitpunkt alles auf Englisch angezeigt):<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-3-1024x300.png\" alt=\"\" class=\"wp-image-11333\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-3-1024x300.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-3-300x88.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-3-768x225.png 768w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-3.png 1193w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Auf der linken Seite werden Sie die folgenden Optionen finden:<\/p>\n\n\n\n<p>* Check for updates: Sollten Sie diese Option ausw\u00e4hlen, \u00fcberpr\u00fcft das System, ob neue Updates verf\u00fcgbar sind<\/p>\n\n\n\n<p>* Change settings: Hier k\u00f6nnen Sie die Einstellungen der Updates \u00e4ndern\/aktualisieren<\/p>\n\n\n\n<p>* View update history: Alle &#8218;erledigten&#8216; und bereits durchgef\u00fchrten Updates werden hier angezeigt<\/p>\n\n\n\n<p>* Zus\u00e4tzlich finden Sie noch die Option \u201eUpdates: frequently asked questions\u201c: Hier k\u00f6nnen mit Hilfe einer Suchbox generelle Fragen gestellt werden.<\/p>\n\n\n\n<p>4.1. Sobald Sie die Option \u201eCheck for updates\u201c ausw\u00e4hlen, startet ein automatischer Suchlauf f\u00fcr neue Windows-Updates. Sollten neue Updates verf\u00fcgbar sein, werden Ihnen diese angezeigt. Sie k\u00f6nnen dann entscheiden, ob Sie diese installieren m\u00f6chten. Sollten Sie \u00c4nderungen an den Einstellungen vornehmen wollen, w\u00e4hlen Sie bitte den Punkt \u201eChange settings\u201c:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"342\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-4-1024x342.png\" alt=\"\" class=\"wp-image-11335\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-4-1024x342.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-4-300x100.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-4-768x256.png 768w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-4.png 1199w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>4.2. Sofern Sie das Dropdownfeld \u00f6ffnen, werden Ihnen drei verschiedene Auswahlm\u00f6glichkeiten angezeigt:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"110\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-5.png\" alt=\"\" class=\"wp-image-11337\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-5.png 520w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-5-300x63.png 300w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/figure>\n\n\n\n<p>Generell wird immer empfohlen, Updates automatisch installieren zu lassen (erste Option). Der Grund hierf\u00fcr ist, dass eventuell Sicherheitsl\u00fccken auf Ihrem Server entstehen k\u00f6nnten, sollten Sie die Version nicht immer auf dem aktuellsten Stand halten.<\/p>\n\n\n\n<p>Sollten Sie die zweite Option \u201e Download updates but let me choose whether to install them\u201c ausw\u00e4hlen, werden die Updates automatisch heruntergeladen. Hier k\u00f6nnen Sie allerdings entscheiden, ob Sie die heruntergeladenen Updates auch installieren m\u00f6chten.<\/p>\n\n\n\n<p>Eine \u00e4hnliche Option ist \u201eCheck for updates but let me choose whether to download and install them\u201c. Hier k\u00f6nnen Sie entscheiden, ob Sie die Updates herunterladen und installieren m\u00f6chten. Sie k\u00f6nnen die Updates hierbei herunterladen, aber zu einem sp\u00e4teren Zeitpunkt installieren.<\/p>\n\n\n\n<p>Nicht zu empfehlen dagegen ist die Option \u201eNever check for updates (not recommended)\u201c. Grund daf\u00fcr ist, dass die Sicherheit des Systems gef\u00e4hrdet ist, sofern Sie die Updates nicht manuell auf dem Laufenden halten. Veraltete Systeme sind beliebte Ziele f\u00fcr &#8218;Hackerangriffe&#8216;, da sich Sicherheitsl\u00fccken ergeben.<\/p>\n\n\n\n<p>4.3. Nachfolgend sehen Sie die Optionen \u201eRecommended updates\u201c und \u201eWho can install updates\u201c. Durch diese Optionen werden Sie \u00fcber empfohlene Updates automatisch informiert. Desweiteren k\u00f6nnen Sie bestimmen, ob alle User diese Updates durchf\u00fchren k\u00f6nnen, sofern Sie nicht als Administrator angemeldet sind.<\/p>\n\n\n\n<p>5. Auf der linken Seite werden Sie au\u00dferdem die Option \u201eView update history\u201c finden. Hier k\u00f6nnen Sie alle Updates einsehen, welche bereits auf Ihrem Server installiert worden sind.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"202\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-6-1024x202.png\" alt=\"\" class=\"wp-image-11339\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-6-1024x202.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-6-300x59.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-6-768x151.png 768w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-6.png 1197w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Sollten Sie ein Update wieder deinstallieren wollen, w\u00e4hlen Sie bitte den Link \u201eInstalled updates\u201c. Sie werden anschlie\u00dfend automatisch weitergeleitet und erhalten eine Liste der Updates, welche bereits installiert worden sind. Hier k\u00f6nnen Sie das entsprechende Update ausw\u00e4hlen und deinstallieren.<\/p>\n\n\n\n<p>Sollten Sie ein Problem mit einem Update feststellen, w\u00e4hlen Sie bitte die Option \u201eTroubleshoot problems with installing updates\u201c. Es wird hierbei automatisch gepr\u00fcft, ob es Probleme mit einem bestimmten Update gibt.<\/p>\n\n\n\n<p>6. Mit der letzten Option \u201eRestore hidden updates\u201c erhalten Sie folgendes Bild:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"148\" src=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-7-1024x148.png\" alt=\"\" class=\"wp-image-11341\" srcset=\"https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-7-1024x148.png 1024w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-7-300x43.png 300w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-7-768x111.png 768w, https:\/\/contabo.com\/blog\/wp-content\/uploads\/2021\/02\/WS-Updates-2008-DE-Bild-7.png 1194w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Updates, welche Sie noch nicht installiert haben, werden Ihnen hier angezeigt. Sie k\u00f6nnen hierbei entscheiden, ob diese Updates nun installiert werden sollen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Tutorial m\u00f6chten wir Ihnen erkl\u00e4ren, wie Sie automatische Updates bei Windows 2008 auf Ihrem Server aktivieren und deaktivieren oder auch den Zeitpunkt f\u00fcr diese Updates bestimmen k\u00f6nnen. 1. Bitte verbinden Sie sich \u00fcber RDP mit Ihrem Server und \u00f6ffnen Sie die Systemsteuerung: 2. Unter dem Punkt \u201eSystem und Sicherheit\u201c finden Sie die gew\u00fcnschte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1399],"tags":[181,845,942,944,947],"ppma_author":[1488],"class_list":["post-4498","post","type-post","status-publish","format-standard","hentry","category-tutorials","tag-contabo","tag-tutorial","tag-windows-server","tag-windows-server-2008","tag-windows-update"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Mike","author_link":"https:\/\/contabo.com\/blog\/de\/author\/mike\/"},"uagb_comment_info":0,"uagb_excerpt":"In diesem Tutorial m\u00f6chten wir Ihnen erkl\u00e4ren, wie Sie automatische Updates bei Windows 2008 auf Ihrem Server aktivieren und deaktivieren oder auch den Zeitpunkt f\u00fcr diese Updates bestimmen k\u00f6nnen. 1. Bitte verbinden Sie sich \u00fcber RDP mit Ihrem Server und \u00f6ffnen Sie die Systemsteuerung: 2. Unter dem Punkt \u201eSystem und Sicherheit\u201c finden Sie die gew\u00fcnschte&hellip;","authors":[{"term_id":1488,"user_id":3,"is_guest":0,"slug":"mike","display_name":"Mike","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/3f53b7f35c06dff01c900c8b80069e7f59329f909731d3b79f9fafe983229098?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts\/4498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=4498"}],"version-history":[{"count":0,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/posts\/4498\/revisions"}],"wp:attachment":[{"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=4498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=4498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=4498"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/contabo.com\/blog\/de\/wp-json\/wp\/v2\/ppma_author?post=4498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}